{"id":9251,"date":"1997-11-09T09:27:00","date_gmt":"1997-11-09T08:27:00","guid":{"rendered":"https:\/\/vendome-investment.com\/?p=9251"},"modified":"2023-02-03T10:56:44","modified_gmt":"2023-02-03T09:56:44","slug":"la-liberte-de-lest-jean-pierre-thomas-tourne-la-page","status":"publish","type":"post","link":"https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/","title":{"rendered":"La Libert\u00e9 de l\u2019est : \u00ab\u00a0Jean-Pierre Thomas tourne la page \u00bb"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-9251","post","type-post","status-publish","format-standard","hentry","category-medias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Libert\u00e9 de l\u2019est : \u00ab\u00a0Jean-Pierre Thomas tourne la page \u00bb &#8226; Thomas Vend\u00f4me Investment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Libert\u00e9 de l\u2019est : \u00ab\u00a0Jean-Pierre Thomas tourne la page \u00bb &#8226; Thomas Vend\u00f4me Investment\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/\" \/>\n<meta property=\"og:site_name\" content=\"Thomas Vend\u00f4me Investment\" \/>\n<meta property=\"article:published_time\" content=\"1997-11-09T08:27:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-03T09:56:44+00:00\" \/>\n<meta name=\"author\" content=\"antoine-tvi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"antoine-tvi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\\\/\"},\"author\":{\"name\":\"antoine-tvi\",\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/#\\\/schema\\\/person\\\/9cd77fb75179368bdc3d8e0d0fdb0736\"},\"headline\":\"La Libert\u00e9 de l\u2019est : \u00ab\u00a0Jean-Pierre Thomas tourne la page \u00bb\",\"datePublished\":\"1997-11-09T08:27:00+00:00\",\"dateModified\":\"2023-02-03T09:56:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\\\/\"},\"wordCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/#organization\"},\"articleSection\":[\"Medias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\\\/\",\"url\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\\\/\",\"name\":\"La Libert\u00e9 de l\u2019est : \u00ab\u00a0Jean-Pierre Thomas tourne la page \u00bb &#8226; Thomas Vend\u00f4me Investment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/#website\"},\"datePublished\":\"1997-11-09T08:27:00+00:00\",\"dateModified\":\"2023-02-03T09:56:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vendome-investment.com\\\/en\\\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Libert\u00e9 de l\u2019est : \u00ab\u00a0Jean-Pierre Thomas tourne la page \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/\",\"name\":\"Thomas Vend\u00f4me Investment\",\"description\":\"founded by Jean-Pierre Thomas\",\"publisher\":{\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/#organization\",\"name\":\"Thomas Vend\u00f4me Investment\",\"url\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vendome-investment.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-tvi.svg\",\"contentUrl\":\"https:\\\/\\\/vendome-investment.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-tvi.svg\",\"width\":1,\"height\":1,\"caption\":\"Thomas Vend\u00f4me Investment\"},\"image\":{\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/thomasvendomeinvestment\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vendome-investment.com\\\/en\\\/#\\\/schema\\\/person\\\/9cd77fb75179368bdc3d8e0d0fdb0736\",\"name\":\"antoine-tvi\",\"sameAs\":[\"https:\\\/\\\/vendome-investment.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Libert\u00e9 de l\u2019est : \u00ab\u00a0Jean-Pierre Thomas tourne la page \u00bb &#8226; Thomas Vend\u00f4me Investment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/","og_locale":"en_US","og_type":"article","og_title":"La Libert\u00e9 de l\u2019est : \u00ab\u00a0Jean-Pierre Thomas tourne la page \u00bb &#8226; Thomas Vend\u00f4me Investment","og_url":"https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/","og_site_name":"Thomas Vend\u00f4me Investment","article_published_time":"1997-11-09T08:27:00+00:00","article_modified_time":"2023-02-03T09:56:44+00:00","author":"antoine-tvi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"antoine-tvi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/#article","isPartOf":{"@id":"https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/"},"author":{"name":"antoine-tvi","@id":"https:\/\/vendome-investment.com\/en\/#\/schema\/person\/9cd77fb75179368bdc3d8e0d0fdb0736"},"headline":"La Libert\u00e9 de l\u2019est : \u00ab\u00a0Jean-Pierre Thomas tourne la page \u00bb","datePublished":"1997-11-09T08:27:00+00:00","dateModified":"2023-02-03T09:56:44+00:00","mainEntityOfPage":{"@id":"https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/"},"wordCount":10,"publisher":{"@id":"https:\/\/vendome-investment.com\/en\/#organization"},"articleSection":["Medias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/","url":"https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/","name":"La Libert\u00e9 de l\u2019est : \u00ab\u00a0Jean-Pierre Thomas tourne la page \u00bb &#8226; Thomas Vend\u00f4me Investment","isPartOf":{"@id":"https:\/\/vendome-investment.com\/en\/#website"},"datePublished":"1997-11-09T08:27:00+00:00","dateModified":"2023-02-03T09:56:44+00:00","breadcrumb":{"@id":"https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vendome-investment.com\/en\/la-liberte-de-lest-jean-pierre-thomas-tourne-la-page\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/vendome-investment.com\/en\/"},{"@type":"ListItem","position":2,"name":"La Libert\u00e9 de l\u2019est : \u00ab\u00a0Jean-Pierre Thomas tourne la page \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/vendome-investment.com\/en\/#website","url":"https:\/\/vendome-investment.com\/en\/","name":"Thomas Vend\u00f4me Investment","description":"founded by Jean-Pierre Thomas","publisher":{"@id":"https:\/\/vendome-investment.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vendome-investment.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/vendome-investment.com\/en\/#organization","name":"Thomas Vend\u00f4me Investment","url":"https:\/\/vendome-investment.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vendome-investment.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/vendome-investment.com\/wp-content\/uploads\/2023\/01\/logo-tvi.svg","contentUrl":"https:\/\/vendome-investment.com\/wp-content\/uploads\/2023\/01\/logo-tvi.svg","width":1,"height":1,"caption":"Thomas Vend\u00f4me Investment"},"image":{"@id":"https:\/\/vendome-investment.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/thomasvendomeinvestment\/"]},{"@type":"Person","@id":"https:\/\/vendome-investment.com\/en\/#\/schema\/person\/9cd77fb75179368bdc3d8e0d0fdb0736","name":"antoine-tvi","sameAs":["https:\/\/vendome-investment.com"]}]}},"_links":{"self":[{"href":"https:\/\/vendome-investment.com\/en\/wp-json\/wp\/v2\/posts\/9251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vendome-investment.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendome-investment.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendome-investment.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vendome-investment.com\/en\/wp-json\/wp\/v2\/comments?post=9251"}],"version-history":[{"count":1,"href":"https:\/\/vendome-investment.com\/en\/wp-json\/wp\/v2\/posts\/9251\/revisions"}],"predecessor-version":[{"id":9252,"href":"https:\/\/vendome-investment.com\/en\/wp-json\/wp\/v2\/posts\/9251\/revisions\/9252"}],"wp:attachment":[{"href":"https:\/\/vendome-investment.com\/en\/wp-json\/wp\/v2\/media?parent=9251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendome-investment.com\/en\/wp-json\/wp\/v2\/categories?post=9251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendome-investment.com\/en\/wp-json\/wp\/v2\/tags?post=9251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}